{"id":38547,"date":"2025-05-13T04:57:33","date_gmt":"2025-05-13T08:57:33","guid":{"rendered":"https:\/\/lalawct.com\/?page_id=38547"},"modified":"2026-01-21T14:47:47","modified_gmt":"2026-01-21T19:47:47","slug":"medical-malpractice-attorney-ct","status":"publish","type":"page","link":"https:\/\/lalawct.com\/es\/medical-malpractice-attorney-ct\/","title":{"rendered":"NEGLIGENCIA M\u00c9DICA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"38547\" class=\"elementor elementor-38547\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf6709d e-con-full e-flex e-con e-parent\" data-id=\"cf6709d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a905c0e e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"a905c0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71f1fef elementor-widget elementor-widget-text-editor\" data-id=\"71f1fef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><br \/><a href=\"https:\/\/www.google.com\/maps\/place\/L.A.+Law,+LLC\/@41.8304317,-72.743377,668m\/data=!3m2!1e3!4b1!4m6!3m5!1s0x89e7ad3417c64557:0x7f81c1c33e61de27!8m2!3d41.8304317!4d-72.7408021!16s%2Fg%2F11j22yqns3?entry=ttu&amp;g_ep=EgoyMDI1MTExNy4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\" data-wplink-edit=\"true\">1 Regency Dr. Suite #302, Bloomfield, CT 06002<\/a>\u00a0|\u00a0<a href=\"tel:8605953163\">860-595-3163<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65659dd e-con-full e-flex e-con e-child\" data-id=\"65659dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf63539 e-grid-align-right elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"bf63539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-cb9a9f3\" href=\"https:\/\/www.facebook.com\/people\/Lawyer-The-Lawyer\/61556617866591\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"19\" viewBox=\"0 0 10 19\" fill=\"none\"><path d=\"M9.12139 10.2516L9.62756 6.95326H6.46275V4.81289C6.46275 3.91054 6.90485 3.03097 8.32227 3.03097H9.76104V0.222829C9.76104 0.222829 8.45539 0 7.20705 0C4.60074 0 2.89713 1.57974 2.89713 4.43949V6.95326H0V10.2516H2.89713V18.225H6.46275V10.2516H9.12139Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-c47062d\" href=\"https:\/\/www.youtube.com\/@lawyerthelawyer\/videos\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"15\" viewBox=\"0 0 21 15\" fill=\"none\"><path d=\"M20.5365 2.23407C20.2967 1.38265 19.6327 0.714903 18.7775 0.478855C17.2028 0.0578815 10.8724 0.0578816 10.8724 0.0578816C10.8724 0.0578816 4.55405 0.0477831 2.96293 0.478855C2.11215 0.715534 1.44503 1.38265 1.20772 2.23407C0.909187 3.84791 0.760868 5.48131 0.767811 7.12229C0.764655 8.75253 0.912343 10.3834 1.20772 11.9872C1.44503 12.8386 2.11215 13.5063 2.96293 13.7462C4.53764 14.1671 10.8724 14.1671 10.8724 14.1671C10.8724 14.1671 17.187 14.1671 18.7775 13.7462C19.6327 13.5063 20.2967 12.8392 20.5365 11.9872C20.8262 10.3834 20.9676 8.75253 20.9575 7.12229C20.9676 5.48131 20.8294 3.84791 20.5365 2.23407ZM8.85025 10.1436V4.08774L14.1197 7.12229L8.85025 10.1436Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-bef666f\" href=\"https:\/\/www.instagram.com\/lawyerthelawyer\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"15\" viewBox=\"0 0 15 15\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M4.90788 0.100189C5.66038 0.0656984 5.90024 0.0578613 7.81636 0.0578613C9.73285 0.0578613 9.97232 0.0660896 10.7244 0.100189C11.4757 0.134289 11.9888 0.253826 12.4375 0.42823C12.9082 0.605436 13.3346 0.883087 13.687 1.24187C14.0458 1.59423 14.3235 2.02063 14.5006 2.49132C14.675 2.94007 14.7942 3.45311 14.8287 4.20403C14.8632 4.95653 14.871 5.19638 14.871 7.1125C14.871 9.02861 14.8628 9.26846 14.8287 10.021C14.7946 10.7719 14.675 11.2849 14.5006 11.7337C14.3204 12.1974 14.0789 12.5912 13.687 12.9831C13.3346 13.3419 12.9082 13.6196 12.4375 13.7968C11.9888 13.9712 11.4757 14.0903 10.7249 14.1248C9.97232 14.1593 9.73246 14.1671 7.81636 14.1671C5.90024 14.1671 5.66038 14.1589 4.90788 14.1248C4.15696 14.0907 3.64393 13.9712 3.19518 13.7968C2.73153 13.6165 2.33765 13.375 1.94572 12.9831C1.58688 12.6308 1.30921 12.2043 1.13209 11.7337C0.957684 11.2849 0.838537 10.7719 0.804047 10.021C0.769556 9.26846 0.761719 9.02899 0.761719 7.1125C0.761719 5.19599 0.769947 4.95653 0.804047 4.20442C0.838146 3.45311 0.957684 2.94007 1.13209 2.49132C1.30929 2.02066 1.58694 1.59428 1.94572 1.24187C2.29808 0.883023 2.72448 0.605353 3.19518 0.42823C3.64393 0.253826 4.15696 0.13468 4.90788 0.100189ZM10.6672 1.37002C9.92332 1.33632 9.69995 1.32887 7.81636 1.32887C5.93277 1.32887 5.70937 1.33632 4.9655 1.37002C4.27767 1.40138 3.90417 1.51621 3.65569 1.61302C3.32647 1.74078 3.09131 1.89363 2.8444 2.14054C2.59789 2.38746 2.44464 2.62261 2.31688 2.95183C2.22007 3.20031 2.10524 3.57382 2.07388 4.26164C2.04017 5.00552 2.03273 5.22891 2.03273 7.1125C2.03273 8.99609 2.04017 9.21947 2.07388 9.96335C2.10524 10.6512 2.22007 11.0247 2.31688 11.2732C2.42989 11.5796 2.61016 11.8568 2.8444 12.0845C3.07201 12.3187 3.34924 12.499 3.65569 12.612C3.90417 12.7088 4.27767 12.8236 4.9655 12.855C5.70937 12.8887 5.93238 12.8962 7.81636 12.8962C9.70033 12.8962 9.92332 12.8887 10.6672 12.855C11.355 12.8236 11.7285 12.7088 11.9771 12.612C12.3063 12.4842 12.5414 12.3314 12.7883 12.0845C13.0226 11.8569 13.2028 11.5796 13.3158 11.2732C13.4127 11.0247 13.5275 10.6512 13.5588 9.96335C13.5926 9.21947 13.6 8.99609 13.6 7.1125C13.6 5.22891 13.5926 5.00552 13.5588 4.26164C13.5275 3.57382 13.4127 3.20031 13.3158 2.95183C13.1881 2.62261 13.0353 2.38746 12.7883 2.14054C12.5414 1.89403 12.3063 1.74078 11.9771 1.61302C11.7285 1.51621 11.355 1.40138 10.6672 1.37002ZM6.91561 9.28719C7.20119 9.40552 7.50724 9.46638 7.81636 9.46638C8.44069 9.46638 9.03938 9.21838 9.4808 8.77695C9.9223 8.33552 10.1703 7.73677 10.1703 7.1125C10.1703 6.48823 9.9223 5.88948 9.4808 5.44804C9.03938 5.0066 8.44069 4.7586 7.81636 4.7586C7.50724 4.7586 7.20119 4.81949 6.91561 4.93778C6.62996 5.05607 6.3705 5.22946 6.15192 5.44804C5.93334 5.66662 5.75995 5.9261 5.64166 6.21169C5.52336 6.49727 5.46248 6.80338 5.46248 7.1125C5.46248 7.42162 5.52336 7.72773 5.64166 8.01331C5.75995 8.2989 5.93334 8.55838 6.15192 8.77695C6.3705 8.99551 6.62996 9.16893 6.91561 9.28719ZM5.25235 4.54847C5.93237 3.86844 6.85468 3.48641 7.81636 3.48641C8.7781 3.48641 9.7004 3.86844 10.3804 4.54847C11.0604 5.22849 11.4424 6.15083 11.4424 7.1125C11.4424 8.07418 11.0604 8.99648 10.3804 9.67654C9.7004 10.3565 8.7781 10.7386 7.81636 10.7386C6.85468 10.7386 5.93237 10.3565 5.25235 9.67654C4.57233 8.99648 4.19029 8.07418 4.19029 7.1125C4.19029 6.15083 4.57233 5.22849 5.25235 4.54847ZM12.2465 4.02666C12.4072 3.86591 12.4975 3.6479 12.4975 3.42057C12.4975 3.19324 12.4072 2.97522 12.2465 2.81448C12.0857 2.65374 11.8677 2.56343 11.6404 2.56343C11.4131 2.56343 11.195 2.65374 11.0343 2.81448C10.8735 2.97522 10.7832 3.19324 10.7832 3.42057C10.7832 3.6479 10.8735 3.86591 11.0343 4.02666C11.195 4.1874 11.4131 4.27771 11.6404 4.27771C11.8677 4.27771 12.0857 4.1874 12.2465 4.02666Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-5c8172c\" href=\"https:\/\/x.com\/LawyerTheLawyer%20\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"15\" viewBox=\"0 0 16 15\" fill=\"none\"><g clip-path=\"url(#clip0_370_2147)\"><path d=\"M12.6844 0.112488H14.9844L9.95954 6.04284L15.8711 14.1125H11.2422L7.61702 9.21816L3.46882 14.1125H1.16726L6.54191 7.76943L0.871094 0.112488H5.61716L8.89419 4.58596L12.6844 0.112488ZM11.8771 12.6909H13.1517L4.9247 1.45946H3.55712L11.8771 12.6909Z\" fill=\"white\"><\/path><\/g><defs><clipPath id=\"clip0_370_2147\"><rect width=\"15\" height=\"14\" fill=\"white\" transform=\"translate(0.871094 0.112488)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-18378a7\" href=\"https:\/\/www.tiktok.com\/@lawyerthelawyer\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"18\" viewBox=\"0 0 16 18\" fill=\"none\"><path d=\"M8.69486 0.553412C9.63077 0.539124 10.5595 0.546268 11.4883 0.539124C11.5455 1.63222 11.9384 2.74674 12.7386 3.51834C13.5388 4.31137 14.6676 4.67573 15.7678 4.79719V7.67638C14.739 7.64066 13.7031 7.42633 12.7672 6.98337C12.3599 6.79762 11.9813 6.56185 11.6098 6.31894C11.6026 8.40511 11.6169 10.4913 11.5955 12.5703C11.5383 13.5705 11.2097 14.5636 10.631 15.3852C9.69507 16.7569 8.07329 17.65 6.40865 17.6785C5.387 17.7357 4.36535 17.4571 3.49373 16.9427C2.05056 16.0925 1.03606 14.535 0.886027 12.8632C0.871738 12.506 0.864594 12.1488 0.878882 11.7987C1.00748 10.4413 1.67906 9.14098 2.72214 8.25508C3.90811 7.22628 5.56561 6.73332 7.11594 7.02624C7.13023 8.08361 7.08737 9.14098 7.08737 10.1984C6.38007 9.96973 5.55132 10.034 4.92976 10.4627C4.47966 10.7556 4.13673 11.2057 3.95812 11.713C3.80809 12.0773 3.85095 12.4774 3.8581 12.8632C4.02956 14.0349 5.15838 15.0208 6.35864 14.9137C7.15881 14.9065 7.92326 14.4421 8.33764 13.7634C8.47338 13.5276 8.62341 13.2847 8.63056 13.0061C8.702 11.7273 8.67342 10.4556 8.68057 9.1767C8.68771 6.29751 8.67342 3.42546 8.69486 0.553412Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92308dd e-flex e-con-boxed e-con e-parent\" data-id=\"92308dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7719b39 e-con-full e-flex e-con e-child\" data-id=\"7719b39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96c73ab elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"96c73ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lalawct.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"929\" src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-2048x929.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-39095\" alt=\"la law logo\" srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-2048x929.png 2048w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-768x349.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-1536x697.png 1536w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-600x272.png 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f5ee62 e-con-full e-flex e-con e-child\" data-id=\"4f5ee62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dce28b7 elementor-nav-menu__align-center elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"dce28b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;toggle_icon_hover_animation&quot;:&quot;pulse&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-dce28b7\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38568\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-lawyers\/\" class=\"elementor-item\">ABOUT US<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38577\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-practice-areas\/\" class=\"elementor-item\">PRACTICE AREAS<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38570\"><a href=\"https:\/\/lalawct.com\/es\/car-accident-attorney-ct\/\" class=\"elementor-sub-item\">CAR ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38584\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-truck-accident-lawyer\/\" class=\"elementor-sub-item\">TRUCK ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38582\"><a href=\"https:\/\/lalawct.com\/es\/motorcycle-accident-attorney-ct\/\" class=\"elementor-sub-item\">MOTORCYCLE ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38578\"><a href=\"https:\/\/lalawct.com\/es\/rideshare-accident-attorney-ct\/\" class=\"elementor-sub-item\">RIDE SHARING<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-48054\"><a href=\"https:\/\/lalawct.com\/es\/social-security-disability-lawyer\/\" class=\"elementor-sub-item\">SOCIAL SECURITY DISABILITY LAWYER<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38573\"><a href=\"https:\/\/lalawct.com\/es\/dog-bite-attorney-ct\/\" class=\"elementor-sub-item\">DOG BITE<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38583\"><a href=\"https:\/\/lalawct.com\/es\/pedestrian-accident-lawyer-ct\/\" class=\"elementor-sub-item\">PEDESTRIAN ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38579\"><a href=\"https:\/\/lalawct.com\/es\/slip-and-fall-lawyer-connecticut\/\" class=\"elementor-sub-item\">SLIP AND FALL<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38569\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-brain-injury\/\" class=\"elementor-sub-item\">BRAIN INJURIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38580\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-workers-compensation-lawyer\/\" class=\"elementor-sub-item\">WORKMANS COMP<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38581\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-wrongful-death-lawyer\/\" class=\"elementor-sub-item\">WRONGFUL DEATH<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40370\"><a href=\"https:\/\/lalawct.com\/es\/medical-malpractice-attorney-ct\/\" class=\"elementor-sub-item\">MEDICAL MALPRACTICE<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-43696\"><a href=\"https:\/\/lalawct.com\/es\/case-results\/\" class=\"elementor-item\">RESULTS<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-41034\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\">LEGAL RESOURCES<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-41033\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-accident-news\/\" class=\"elementor-sub-item\">NEWS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-41701\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-lawyer-media\/\" class=\"elementor-sub-item\">MEDIA<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38574\"><a href=\"https:\/\/lalawct.com\/es\/personal-injury-faqs\/\" class=\"elementor-sub-item\">FAQs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40304\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-law-blog\/\" class=\"elementor-sub-item\">BLOG<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-41233\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-legal-guides\/\" class=\"elementor-sub-item\">GUIDES<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38571\"><a href=\"https:\/\/lalawct.com\/es\/client-testimonials\/\" class=\"elementor-item\">TESTIMONIALS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38572\"><a href=\"https:\/\/lalawct.com\/es\/contact-connecticut-injury-lawyer\/\" class=\"elementor-item\">CONTACT US<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open elementor-animation-pulse e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close elementor-animation-pulse e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-dce28b7\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38568\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-lawyers\/\" class=\"elementor-item\" tabindex=\"-1\">ABOUT US<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-38577\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-practice-areas\/\" class=\"elementor-item\" tabindex=\"-1\">PRACTICE AREAS<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38570\"><a href=\"https:\/\/lalawct.com\/es\/car-accident-attorney-ct\/\" class=\"elementor-sub-item\" tabindex=\"-1\">CAR ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38584\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-truck-accident-lawyer\/\" class=\"elementor-sub-item\" tabindex=\"-1\">TRUCK ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38582\"><a href=\"https:\/\/lalawct.com\/es\/motorcycle-accident-attorney-ct\/\" class=\"elementor-sub-item\" tabindex=\"-1\">MOTORCYCLE ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38578\"><a href=\"https:\/\/lalawct.com\/es\/rideshare-accident-attorney-ct\/\" class=\"elementor-sub-item\" tabindex=\"-1\">RIDE SHARING<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-48054\"><a href=\"https:\/\/lalawct.com\/es\/social-security-disability-lawyer\/\" class=\"elementor-sub-item\" tabindex=\"-1\">SOCIAL SECURITY DISABILITY LAWYER<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38573\"><a href=\"https:\/\/lalawct.com\/es\/dog-bite-attorney-ct\/\" class=\"elementor-sub-item\" tabindex=\"-1\">DOG BITE<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38583\"><a href=\"https:\/\/lalawct.com\/es\/pedestrian-accident-lawyer-ct\/\" class=\"elementor-sub-item\" tabindex=\"-1\">PEDESTRIAN ACCIDENTS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38579\"><a href=\"https:\/\/lalawct.com\/es\/slip-and-fall-lawyer-connecticut\/\" class=\"elementor-sub-item\" tabindex=\"-1\">SLIP AND FALL<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38569\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-brain-injury\/\" class=\"elementor-sub-item\" tabindex=\"-1\">BRAIN INJURIES<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38580\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-workers-compensation-lawyer\/\" class=\"elementor-sub-item\" tabindex=\"-1\">WORKMANS COMP<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38581\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-wrongful-death-lawyer\/\" class=\"elementor-sub-item\" tabindex=\"-1\">WRONGFUL DEATH<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40370\"><a href=\"https:\/\/lalawct.com\/es\/medical-malpractice-attorney-ct\/\" class=\"elementor-sub-item\" tabindex=\"-1\">MEDICAL MALPRACTICE<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-43696\"><a href=\"https:\/\/lalawct.com\/es\/case-results\/\" class=\"elementor-item\" tabindex=\"-1\">RESULTS<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-41034\"><a href=\"#\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">LEGAL RESOURCES<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-41033\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-accident-news\/\" class=\"elementor-sub-item\" tabindex=\"-1\">NEWS<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-41701\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-lawyer-media\/\" class=\"elementor-sub-item\" tabindex=\"-1\">MEDIA<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38574\"><a href=\"https:\/\/lalawct.com\/es\/personal-injury-faqs\/\" class=\"elementor-sub-item\" tabindex=\"-1\">FAQs<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40304\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-personal-injury-law-blog\/\" class=\"elementor-sub-item\" tabindex=\"-1\">BLOG<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-41233\"><a href=\"https:\/\/lalawct.com\/es\/connecticut-legal-guides\/\" class=\"elementor-sub-item\" tabindex=\"-1\">GUIDES<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38571\"><a href=\"https:\/\/lalawct.com\/es\/client-testimonials\/\" class=\"elementor-item\" tabindex=\"-1\">TESTIMONIALS<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38572\"><a href=\"https:\/\/lalawct.com\/es\/contact-connecticut-injury-lawyer\/\" class=\"elementor-item\" tabindex=\"-1\">CONTACT US<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05a067b e-flex e-con-boxed e-con e-parent\" data-id=\"05a067b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c8b722f e-con-full e-flex e-con e-child\" data-id=\"c8b722f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71e40bf elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"71e40bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Medical Malpractice Lawyers Fighting for Injured Patients<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c16703 elementor-mobile-align-center elementor-widget-mobile__width-initial elementor-widget elementor-widget-button\" data-id=\"2c16703\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#injury\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">REQUEST A FREE CASE REVIEW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb77038 e-flex e-con-boxed e-con e-parent\" data-id=\"eb77038\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea4a607 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"ea4a607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">When a Doctor\u2019s Mistake Causes Harm, You Deserve More Than an Apology\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6add7a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b6add7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Medical professionals are trusted to help\u2014not hurt. But when hospitals, doctors, or nurses fail to follow the standard of care, the consequences can be life-changing. At L.A. LAW, we represent victims of medical malpractice across Connecticut and help them recover compensation for pain, <a href=\"https:\/\/lalawct.com\/emotional-trauma-injury-lawyer-connecticut\/\"><span style=\"text-decoration: underline; color: #ff6600;\"><strong>trauma<\/strong><\/span><\/a>, and financial loss. You focus on healing\u2014we\u2019ll take care of the legal fight.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d660ae elementor-widget elementor-widget-button\" data-id=\"1d660ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/contact-personal-injury-lawyer-ct\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SPEAK TO A LAWYER NOW<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-543155c e-flex e-con-boxed e-con e-parent\" data-id=\"543155c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-67af0de e-con-full e-flex e-con e-child\" data-id=\"67af0de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7b0f05 elementor-widget elementor-widget-heading\" data-id=\"e7b0f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Medical Negligence Cases Are Complex\u2014We Make Them Clear and Winnable<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9aaf6f6 elementor-widget elementor-widget-text-editor\" data-id=\"9aaf6f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Malpractice cases are unlike any other. You\u2019re going up against powerful healthcare institutions and their insurance teams. That\u2019s why we build every case with expert support and deep attention to medical detail. Our process includes:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1527730 e-con-full e-flex e-con e-child\" data-id=\"1527730\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccb1d24 elementor-position-inline-start elementor-widget__width-initial elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ccb1d24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIdentifying breaches in the standard of care\u200b\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63b84e3 elementor-position-inline-start elementor-widget__width-initial elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"63b84e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFight for full compensation\u2014past, present, and future\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ffa128 elementor-position-inline-start elementor-widget__width-initial elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"0ffa128\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tInvestigating hospital protocols and decision-making\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d89b8d elementor-widget elementor-widget-button\" data-id=\"3d89b8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/contact-personal-injury-lawyer-ct\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SEE WHY CLIENTS CHOOSE US<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec608a9 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"ec608a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2424598 elementor-widget elementor-widget-image\" data-id=\"2424598\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"524\" height=\"778\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/SUPPORT-.png\" class=\"attachment-full size-full wp-image-38552 lazyload\" alt=\"social security disability lawyer\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 524px; --smush-placeholder-aspect-ratio: 524\/778;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dbd070 injury e-flex e-con-boxed e-con e-parent\" data-id=\"0dbd070\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-32ca922 e-con-full e-flex e-con e-child\" data-id=\"32ca922\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aa800e5 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"aa800e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Injured? Get <span style=\"color: #FF6600\">Maximum<\/span><br><span style=\"color: #FF6600\">Compensation<\/span> For Your Injury!\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6742c9c elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6742c9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fill out this fast and easy form to get your 100% Free Case Evaluation &#8211; 60 Seconds Max<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05113c8 e-con-full e-flex e-con e-child\" data-id=\"05113c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b95b1 elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"b0b95b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Request a <span style=\"color:#FF6600\">FREE<\/span> Case Review<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed86f7b elementor-widget-widescreen__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ed86f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>Information needed to complete the evaluation\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df221e1 elementor-widget elementor-widget-spacer\" data-id=\"df221e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-890e7c9 elementor-widget-widescreen__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-html\" data-id=\"890e7c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Elfsight Form Builder | Intake Form - LA LAW  -->\n<script src=\"https:\/\/static.elfsight.com\/platform\/platform.js\" async><\/script>\n<div class=\"elfsight-app-ef457957-a42f-4ff7-bd90-86119990ff9e\" data-elfsight-app-lazy><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6082aa0 e-flex e-con-boxed e-con e-parent\" data-id=\"6082aa0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0020ce9 e-con-full e-flex e-con e-child\" data-id=\"0020ce9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4fcac3 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"a4fcac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Why Injury Victims Across  \nConnecticut Trust L.A. LAW<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a194935 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a194935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Medical malpractice cases are often denied, ignored, or buried in bureaucracy. At L.A. LAW, we pursue these cases with urgency and precision.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28c8a68 elementor-position-inline-start elementor-widget__width-initial elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"28c8a68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"78\" height=\"77\" viewBox=\"0 0 78 77\" fill=\"none\"><path d=\"M67.2725 35.3418C67.6234 35.3418 67.9116 35.229 68.1372 35.0034C68.3628 34.7778 68.4756 34.4896 68.4756 34.1387V29.8525H70.5811C70.8818 29.8525 71.145 29.7397 71.3706 29.5142C71.5962 29.2886 71.709 29.0254 71.709 28.7246V23.2354C71.709 23.1852 71.6964 23.1226 71.6714 23.0474C71.6463 22.9722 71.6338 22.8844 71.6338 22.7842C71.6338 22.7842 71.6087 22.7842 71.5586 22.7842C71.5586 22.7341 71.5461 22.6839 71.521 22.6338C71.4959 22.5837 71.4583 22.5335 71.4082 22.4834C71.3581 22.4834 71.333 22.4709 71.333 22.4458C71.333 22.4207 71.3079 22.4082 71.2578 22.4082C71.2578 22.3581 71.2453 22.3205 71.2202 22.2954C71.1952 22.2703 71.1576 22.2578 71.1074 22.2578L39.6006 3.75977C39.4001 3.65951 39.1995 3.60938 38.999 3.60938C38.7985 3.60938 38.598 3.65951 38.3975 3.75977L6.89062 22.2578C6.84049 22.2578 6.8029 22.2703 6.77783 22.2954C6.75277 22.3205 6.74023 22.3581 6.74023 22.4082C6.6901 22.4082 6.66504 22.4207 6.66504 22.4458C6.66504 22.4709 6.63997 22.4834 6.58984 22.4834C6.53971 22.5335 6.50212 22.5837 6.47705 22.6338C6.45199 22.6839 6.43945 22.7341 6.43945 22.7842C6.38932 22.7842 6.36426 22.7842 6.36426 22.7842C6.36426 22.7842 6.36426 22.8092 6.36426 22.8594C6.36426 22.9095 6.35173 22.9722 6.32666 23.0474C6.3016 23.1226 6.28906 23.1852 6.28906 23.2354V28.7246C6.28906 29.0254 6.40186 29.2886 6.62744 29.5142C6.85303 29.7397 7.11621 29.8525 7.41699 29.8525H9.52246V34.1387C9.52246 34.4896 9.63525 34.7778 9.86084 35.0034C10.0864 35.229 10.3747 35.3418 10.7256 35.3418H11.7031V59.1035H10.7256C10.3747 59.1035 10.0864 59.2163 9.86084 59.4419C9.63525 59.6675 9.52246 59.9307 9.52246 60.2314V64.5176H7.41699C7.11621 64.5176 6.85303 64.6304 6.62744 64.856C6.40186 65.0815 6.28906 65.3698 6.28906 65.7207V72.2627C6.28906 72.5635 6.40186 72.8267 6.62744 73.0522C6.85303 73.2778 7.11621 73.3906 7.41699 73.3906H70.5811C70.8818 73.3906 71.145 73.2778 71.3706 73.0522C71.5962 72.8267 71.709 72.5635 71.709 72.2627V65.7207C71.709 65.3698 71.5962 65.0815 71.3706 64.856C71.145 64.6304 70.8818 64.5176 70.5811 64.5176H68.4756V60.2314C68.4756 59.9307 68.3628 59.6675 68.1372 59.4419C67.9116 59.2163 67.6234 59.1035 67.2725 59.1035H66.2949V35.3418H67.2725ZM66.1445 33.0107H55.3916V29.8525H66.1445V33.0107ZM54.2637 59.1035C53.9128 59.1035 53.6245 59.2163 53.3989 59.4419C53.1733 59.6675 53.0605 59.9307 53.0605 60.2314V64.5176H24.9375V60.2314C24.9375 59.9307 24.8247 59.6675 24.5991 59.4419C24.3735 59.2163 24.0853 59.1035 23.7344 59.1035H22.7568V35.3418H23.7344C24.0853 35.3418 24.3735 35.229 24.5991 35.0034C24.8247 34.7778 24.9375 34.4896 24.9375 34.1387V29.8525H53.0605V34.1387C53.0605 34.4896 53.1733 34.7778 53.3989 35.0034C53.6245 35.229 53.9128 35.3418 54.2637 35.3418H55.2412V59.1035H54.2637ZM38.999 6.09082L66.2949 22.1074H58.9258L39.6006 10.3018C39.4001 10.2015 39.1995 10.1514 38.999 10.1514C38.7985 10.1514 38.598 10.2015 38.3975 10.3018L33.4346 13.3096C33.1338 13.5101 32.9458 13.7607 32.8706 14.0615C32.7954 14.3623 32.8581 14.6631 33.0586 14.9639C33.209 15.2145 33.4346 15.3774 33.7354 15.4526C34.0361 15.5278 34.3369 15.4902 34.6377 15.3398L38.999 12.6328L54.4141 22.1074H23.584L26.2158 20.4531C26.5166 20.3027 26.7046 20.0646 26.7798 19.7388C26.855 19.4129 26.8174 19.1247 26.667 18.874C26.4665 18.5732 26.2158 18.3853 25.915 18.3101C25.6143 18.2349 25.3135 18.2975 25.0127 18.498L19.0723 22.1074H11.7031L38.999 6.09082ZM8.62012 24.4385H69.3779V27.5215H8.62012V24.4385ZM22.6064 29.8525V33.0107H11.8535V29.8525H22.6064ZM14.0342 35.3418H20.4258V59.1035H14.0342V35.3418ZM11.8535 61.4346H22.6064V64.5176H11.8535V61.4346ZM69.3779 71.0596H8.62012V66.8486H69.3779V71.0596ZM55.3916 64.5176V61.4346H66.1445V64.5176H55.3916ZM63.9639 59.1035H57.5723V35.3418H63.9639V59.1035ZM29.374 18.3477C29.4743 18.3477 29.5745 18.3351 29.6748 18.3101C29.7751 18.285 29.8753 18.2474 29.9756 18.1973L30.8779 17.5957C31.1787 17.4453 31.3667 17.2197 31.4419 16.9189C31.5171 16.6182 31.4795 16.3174 31.3291 16.0166C31.1286 15.7659 30.8779 15.5905 30.5771 15.4902C30.2764 15.39 29.9756 15.4401 29.6748 15.6406L28.7725 16.167C28.4717 16.3675 28.2837 16.6182 28.2085 16.9189C28.1333 17.2197 28.196 17.5205 28.3965 17.8213C28.4967 17.9717 28.6346 18.097 28.8101 18.1973C28.9855 18.2975 29.1735 18.3477 29.374 18.3477ZM39.6758 46.0195C39.0742 45.7689 38.6732 45.5558 38.4727 45.3804C38.2721 45.2049 38.1719 44.9919 38.1719 44.7412C38.1719 44.641 38.1969 44.5156 38.2471 44.3652C38.2972 44.2148 38.4476 44.0645 38.6982 43.9141C38.999 43.8138 39.3249 43.7762 39.6758 43.8013C40.0267 43.8263 40.3024 43.9391 40.5029 44.1396C40.7034 44.3402 40.9666 44.4404 41.2925 44.4404C41.6183 44.4404 41.9066 44.3402 42.1572 44.1396C42.3577 43.889 42.458 43.6007 42.458 43.2749C42.458 42.9491 42.3577 42.6859 42.1572 42.4854C41.9066 42.2347 41.6309 42.0342 41.3301 41.8838C41.0293 41.7334 40.7285 41.6331 40.4277 41.583V40.7559C40.4277 40.4551 40.3149 40.1919 40.0894 39.9663C39.8638 39.7407 39.5755 39.6279 39.2246 39.6279C38.9238 39.6279 38.6606 39.7407 38.4351 39.9663C38.2095 40.1919 38.0967 40.4551 38.0967 40.7559V41.7334C38.0465 41.7334 37.9964 41.7334 37.9463 41.7334C37.8962 41.7334 37.8711 41.7585 37.8711 41.8086C37.2194 42.0592 36.7181 42.4478 36.3672 42.9741C36.0163 43.5005 35.8408 44.0895 35.8408 44.7412C35.8408 45.7438 36.1667 46.4832 36.8184 46.9595C37.4701 47.4357 38.0967 47.8242 38.6982 48.125C39.3499 48.4258 39.8011 48.6764 40.0518 48.877C40.3024 49.0775 40.4277 49.3532 40.4277 49.7041C40.4277 49.9548 40.2899 50.1678 40.0142 50.3433C39.7384 50.5187 39.4753 50.6064 39.2246 50.6064C38.8737 50.6064 38.4852 50.5187 38.0591 50.3433C37.633 50.1678 37.3698 50.0299 37.2695 49.9297C37.0189 49.7292 36.7306 49.6289 36.4048 49.6289C36.0789 49.6289 35.8158 49.7292 35.6152 49.9297C35.3646 50.1803 35.2393 50.4561 35.2393 50.7568C35.2393 51.0576 35.3646 51.3333 35.6152 51.584C35.8659 51.8346 36.2168 52.0728 36.668 52.2983C37.1191 52.5239 37.5954 52.6868 38.0967 52.7871V53.6143C38.0967 53.915 38.2095 54.1908 38.4351 54.4414C38.6606 54.6921 38.9238 54.8174 39.2246 54.8174C39.5755 54.8174 39.8638 54.6921 40.0894 54.4414C40.3149 54.1908 40.4277 53.915 40.4277 53.6143V52.7119C41.0293 52.5114 41.5682 52.1479 42.0444 51.6216C42.5207 51.0952 42.7588 50.4561 42.7588 49.7041C42.7588 48.6012 42.3953 47.7866 41.6685 47.2603C40.9416 46.7339 40.2773 46.3203 39.6758 46.0195ZM38.999 33.2363C35.139 33.2363 31.8429 34.6024 29.1108 37.3345C26.3787 40.0666 25.0127 43.3626 25.0127 47.2227C25.0127 51.0827 26.3787 54.3662 29.1108 57.0732C31.8429 59.7803 35.139 61.1338 38.999 61.1338C42.8591 61.1338 46.1551 59.7803 48.8872 57.0732C51.6193 54.3662 52.9854 51.0827 52.9854 47.2227C52.9854 43.3626 51.6193 40.0666 48.8872 37.3345C46.1551 34.6024 42.8591 33.2363 38.999 33.2363ZM38.999 58.8027C35.7907 58.8027 33.0461 57.6748 30.7651 55.4189C28.4842 53.1631 27.3438 50.431 27.3438 47.2227C27.3438 44.0143 28.4842 41.2697 30.7651 38.9888C33.0461 36.7078 35.7907 35.5674 38.999 35.5674C42.2074 35.5674 44.952 36.7078 47.2329 38.9888C49.5138 41.2697 50.6543 44.0143 50.6543 47.2227C50.6543 50.431 49.5138 53.1631 47.2329 55.4189C44.952 57.6748 42.2074 58.8027 38.999 58.8027Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWe have access to respected medical experts and legal specialists\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b67fcc elementor-position-inline-start elementor-widget__width-initial elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"1b67fcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"81\" height=\"81\" viewBox=\"0 0 81 81\" fill=\"none\"><path d=\"M75.9375 39.2344C75.6211 39.2344 75.3442 39.3662 75.1069 39.6299C74.8696 39.8936 74.751 40.1836 74.751 40.5V41.6074C74.751 41.9766 74.8696 42.2798 75.1069 42.5171C75.3442 42.7544 75.6211 42.873 75.9375 42.873C76.3066 42.873 76.6099 42.7544 76.8472 42.5171C77.0845 42.2798 77.2031 41.9766 77.2031 41.6074V40.5C77.2031 40.1836 77.0845 39.8936 76.8472 39.6299C76.6099 39.3662 76.3066 39.2344 75.9375 39.2344ZM75.9375 30.1377H70.2422C69.1875 30.1377 68.2515 30.4541 67.4341 31.0869C66.6167 31.7197 66.0498 32.5371 65.7334 33.5391H55.6084L47.3818 29.7422C46.96 29.5312 46.5381 29.373 46.1162 29.2676C45.6943 29.1621 45.2725 29.083 44.8506 29.0303L44.0596 17.6396L49.5176 17.0859L46.2744 22.7021C46.2744 22.7549 46.2612 22.8076 46.2349 22.8604C46.2085 22.9131 46.1953 22.9922 46.1953 23.0977C46.1953 23.0977 46.1821 23.0977 46.1558 23.0977C46.1294 23.0977 46.1162 23.0977 46.1162 23.0977C46.1162 23.2031 46.1162 23.2954 46.1162 23.3745C46.1162 23.4536 46.1426 23.5459 46.1953 23.6514L46.9072 26.499C47.0654 27.29 47.4609 27.936 48.0938 28.437C48.7266 28.938 49.4648 29.1885 50.3086 29.1885H53.5518C54.3955 29.1885 55.1338 28.938 55.7666 28.437C56.3994 27.936 56.8213 27.29 57.0322 26.499L57.7441 23.6514C57.7441 23.5459 57.7441 23.4536 57.7441 23.3745C57.7441 23.2954 57.7441 23.2031 57.7441 23.0977C57.6914 23.0449 57.665 22.979 57.665 22.8999C57.665 22.8208 57.6387 22.7549 57.5859 22.7021L54.1055 16.6904L55.4502 16.5322C55.8193 16.5322 56.1094 16.4136 56.3203 16.1763C56.5312 15.939 56.6367 15.6621 56.6367 15.3457V14.1592C56.6367 13.21 56.2939 12.3926 55.6084 11.707C54.9229 11.0215 54.0791 10.6787 53.0771 10.6787H43.5059C43.5059 10.626 43.4927 10.5864 43.4663 10.5601C43.4399 10.5337 43.4004 10.5205 43.3477 10.5205C43.5586 10.2568 43.73 9.94043 43.8618 9.57129C43.9937 9.20215 44.0596 8.83301 44.0596 8.46387C44.0596 7.51465 43.73 6.49951 43.0708 5.41846C42.4116 4.3374 41.5547 3.79688 40.5 3.79688C39.4453 3.79688 38.5884 4.3374 37.9292 5.41846C37.27 6.49951 36.9404 7.51465 36.9404 8.46387C36.9404 8.83301 37.0063 9.20215 37.1382 9.57129C37.27 9.94043 37.4414 10.2568 37.6523 10.5205C37.5996 10.5205 37.5601 10.5337 37.5337 10.5601C37.5073 10.5864 37.4941 10.626 37.4941 10.6787H27.9229C26.9209 10.6787 26.0771 11.0215 25.3916 11.707C24.7061 12.3926 24.3633 13.21 24.3633 14.1592V15.3457C24.3633 15.6621 24.4819 15.939 24.7192 16.1763C24.9565 16.4136 25.2334 16.5322 25.5498 16.5322L26.8945 16.6904L23.4141 22.7021C23.3613 22.7549 23.335 22.8208 23.335 22.8999C23.335 22.979 23.3086 23.0449 23.2559 23.0977C23.2559 23.2031 23.2559 23.2954 23.2559 23.3745C23.2559 23.4536 23.2559 23.5459 23.2559 23.6514L23.9678 26.499C24.1787 27.29 24.6006 27.936 25.2334 28.437C25.8662 28.938 26.6045 29.1885 27.4482 29.1885H30.6914C31.5352 29.1885 32.2734 28.938 32.9062 28.437C33.5391 27.936 33.9346 27.29 34.0928 26.499L34.8047 23.6514C34.8574 23.5459 34.8838 23.4536 34.8838 23.3745C34.8838 23.2954 34.8838 23.2031 34.8838 23.0977C34.8838 23.0977 34.8706 23.0977 34.8442 23.0977C34.8179 23.0977 34.8047 23.0977 34.8047 23.0977C34.8047 23.0449 34.7915 22.979 34.7651 22.8999C34.7388 22.8208 34.7256 22.7549 34.7256 22.7021L31.4824 17.0859L36.9404 17.6396L36.0703 31.2451H24.6797C24.1523 31.2451 23.625 31.311 23.0977 31.4429C22.5703 31.5747 22.0693 31.7461 21.5947 31.957L18.5098 33.5391H15.1875C14.8711 32.5371 14.2778 31.7197 13.4077 31.0869C12.5376 30.4541 11.5488 30.1377 10.4414 30.1377H5.0625C4.69336 30.1377 4.39014 30.2563 4.15283 30.4937C3.91553 30.731 3.79688 31.0078 3.79688 31.3242V61.0664C3.79688 61.4355 3.91553 61.7388 4.15283 61.9761C4.39014 62.2134 4.69336 62.332 5.0625 62.332H10.4414C11.5488 62.332 12.5376 62.0024 13.4077 61.3433C14.2778 60.6841 14.8711 59.8799 15.1875 58.9307L17.165 58.8516L19.6963 60.9082C19.0107 61.8047 18.7339 62.8066 18.8657 63.9141C18.9976 65.0215 19.5117 65.918 20.4082 66.6035C20.6719 66.8145 20.9487 66.9858 21.2388 67.1177C21.5288 67.2495 21.832 67.3418 22.1484 67.3945C21.8848 68.1855 21.8584 69.0029 22.0693 69.8467C22.2803 70.6904 22.7285 71.376 23.4141 71.9033C23.8359 72.2197 24.2578 72.457 24.6797 72.6152C25.1016 72.7734 25.5234 72.8525 25.9453 72.8525C26.3672 72.8525 26.7627 72.7866 27.1318 72.6548C27.501 72.5229 27.8438 72.3516 28.1602 72.1406C28.3184 72.457 28.4897 72.7339 28.6743 72.9712C28.8589 73.2085 29.083 73.4326 29.3467 73.6436C29.7158 73.96 30.1245 74.1973 30.5728 74.3555C31.021 74.5137 31.4561 74.5928 31.8779 74.5928C32.0889 74.5928 32.313 74.5664 32.5503 74.5137C32.7876 74.4609 33.0117 74.4082 33.2227 74.3555C33.3281 74.7246 33.4995 75.0806 33.7368 75.4233C33.9741 75.7661 34.251 76.0693 34.5674 76.333C34.9365 76.5967 35.332 76.8076 35.7539 76.9658C36.1758 77.124 36.624 77.2031 37.0986 77.2031C37.1514 77.2031 37.2173 77.2031 37.2964 77.2031C37.3755 77.2031 37.4678 77.2031 37.5732 77.2031C38.1006 77.0977 38.6016 76.9131 39.0762 76.6494C39.5508 76.3857 39.9727 76.043 40.3418 75.6211L42.873 72.3779L44.6133 73.8809C44.9824 74.25 45.3911 74.5137 45.8394 74.6719C46.2876 74.8301 46.7754 74.9092 47.3027 74.9092C47.8828 74.9092 48.4497 74.7905 49.0034 74.5532C49.5571 74.3159 50.0186 73.96 50.3877 73.4854C50.6514 73.1689 50.8623 72.8262 51.0205 72.457C51.1787 72.0879 51.2842 71.6924 51.3369 71.2705C51.4424 71.2705 51.5347 71.2837 51.6138 71.3101C51.6929 71.3364 51.7852 71.3496 51.8906 71.3496C52.4707 71.3496 53.0244 71.231 53.5518 70.9937C54.0791 70.7563 54.5537 70.4004 54.9756 69.9258C55.1865 69.6621 55.3711 69.3853 55.5293 69.0952C55.6875 68.8052 55.793 68.502 55.8457 68.1855C56.1094 68.291 56.3599 68.3701 56.5972 68.4229C56.8345 68.4756 57.085 68.502 57.3486 68.502C57.9287 68.502 58.4956 68.3833 59.0493 68.146C59.603 67.9087 60.0645 67.5527 60.4336 67.0781C61.0137 66.3926 61.3433 65.6279 61.4224 64.7842C61.5015 63.9404 61.3301 63.1494 60.9082 62.4111C61.2246 62.2529 61.5146 62.0815 61.7783 61.897C62.042 61.7124 62.2793 61.5146 62.4902 61.3037C62.7539 60.9346 62.978 60.5522 63.1626 60.1567C63.3472 59.7612 63.4395 59.3525 63.4395 58.9307H65.7334C66.0498 59.8799 66.6167 60.6841 67.4341 61.3433C68.2515 62.0024 69.1875 62.332 70.2422 62.332H75.9375C76.3066 62.332 76.6099 62.2134 76.8472 61.9761C77.0845 61.7388 77.2031 61.4355 77.2031 61.0664V46.1953C77.2031 45.8789 77.0845 45.6021 76.8472 45.3647C76.6099 45.1274 76.3066 45.0088 75.9375 45.0088C75.6211 45.0088 75.3442 45.1274 75.1069 45.3647C74.8696 45.6021 74.751 45.8789 74.751 46.1953V59.8799H70.2422C69.6621 59.8799 69.1479 59.6558 68.6997 59.2075C68.2515 58.7593 68.0273 58.2451 68.0273 57.665V34.8047C68.0273 34.1719 68.2515 33.6445 68.6997 33.2227C69.1479 32.8008 69.6621 32.5898 70.2422 32.5898H74.751V35.9121C74.751 36.2812 74.8696 36.5845 75.1069 36.8218C75.3442 37.0591 75.6211 37.1777 75.9375 37.1777C76.3066 37.1777 76.6099 37.0591 76.8472 36.8218C77.0845 36.5845 77.2031 36.2812 77.2031 35.9121V31.3242C77.2031 31.0078 77.0845 30.731 76.8472 30.4937C76.6099 30.2563 76.3066 30.1377 75.9375 30.1377ZM54.5801 25.8662C54.5273 26.1299 54.4087 26.3276 54.2241 26.4595C54.0396 26.5913 53.8154 26.6572 53.5518 26.6572H50.3086C50.0449 26.6572 49.8208 26.5913 49.6362 26.4595C49.4517 26.3276 49.333 26.1299 49.2803 25.8662L48.9639 24.6006H54.8965L54.5801 25.8662ZM49.5176 22.0693L51.9697 17.7979L54.3428 22.0693H49.5176ZM29.0303 17.7979L31.4824 22.0693H26.6572L29.0303 17.7979ZM31.7197 25.8662C31.667 26.1299 31.5483 26.3276 31.3638 26.4595C31.1792 26.5913 30.9551 26.6572 30.6914 26.6572H27.4482C27.1846 26.6572 26.9604 26.5913 26.7759 26.4595C26.5913 26.3276 26.4727 26.1299 26.4199 25.8662L26.1035 24.6006H32.0361L31.7197 25.8662ZM54.8174 35.9121C54.9229 35.9648 55.0151 35.9912 55.0942 35.9912C55.1733 35.9912 55.2656 35.9912 55.3711 35.9912H65.5752V56.3994H62.8066C62.7012 56.2412 62.5957 56.083 62.4902 55.9248C62.3848 55.7666 62.2529 55.6348 62.0947 55.5293L42.7939 38.7598C42.7412 38.7598 42.7148 38.7598 42.7148 38.7598C42.7148 38.7598 42.7017 38.7598 42.6753 38.7598C42.6489 38.7598 42.6357 38.7334 42.6357 38.6807C42.3721 38.5225 42.082 38.4565 41.7656 38.4829C41.4492 38.5093 41.1855 38.6543 40.9746 38.918C40.9746 38.918 40.9746 38.9443 40.9746 38.9971L38.127 42.5566C37.8633 42.9258 37.5337 43.2158 37.1382 43.4268C36.7427 43.6377 36.334 43.7695 35.9121 43.8223C35.4902 43.875 35.0684 43.8354 34.6465 43.7036C34.2246 43.5718 33.8291 43.374 33.46 43.1104L32.5898 42.4775L39.6299 33.5391C39.6826 33.5391 39.7222 33.5127 39.7485 33.46C39.7749 33.4072 39.7881 33.3809 39.7881 33.3809C39.7881 33.3809 39.8013 33.3809 39.8276 33.3809C39.854 33.3809 39.8672 33.3809 39.8672 33.3809C40.3418 32.8008 40.9087 32.3525 41.5679 32.0361C42.2271 31.7197 42.9258 31.5352 43.6641 31.4824C43.6641 31.4824 43.6772 31.4824 43.7036 31.4824C43.73 31.4824 43.7432 31.4824 43.7432 31.4824C43.7959 31.4824 43.8486 31.4824 43.9014 31.4824C43.9541 31.4824 43.9805 31.4824 43.9805 31.4824C44.4023 31.4824 44.811 31.522 45.2065 31.6011C45.6021 31.6802 45.9844 31.7988 46.3535 31.957L54.8174 35.9121ZM42.7148 14.1592C42.7148 14.792 42.4907 15.3193 42.0425 15.7412C41.5942 16.1631 41.0801 16.374 40.5 16.374C39.9199 16.374 39.4058 16.1631 38.9575 15.7412C38.5093 15.3193 38.2852 14.792 38.2852 14.1592C38.2852 13.5791 38.5093 13.0781 38.9575 12.6562C39.4058 12.2344 39.9199 12.0234 40.5 12.0234C41.0801 12.0234 41.5942 12.2344 42.0425 12.6562C42.4907 13.0781 42.7148 13.5791 42.7148 14.1592ZM40.5 18.8262C40.7109 18.8262 40.9087 18.813 41.0933 18.7866C41.2778 18.7603 41.4756 18.7207 41.6865 18.668L42.3193 29.1094C41.6338 29.2676 40.9614 29.5181 40.3022 29.8608C39.6431 30.2036 39.0498 30.6123 38.5225 31.0869L39.3135 18.668C39.5244 18.7207 39.7222 18.7603 39.9067 18.7866C40.0913 18.813 40.2891 18.8262 40.5 18.8262ZM54.1055 14.1592L45.0879 15.0293C45.0879 14.8711 45.1011 14.7261 45.1274 14.5942C45.1538 14.4624 45.167 14.3174 45.167 14.1592C45.167 14.001 45.1538 13.8296 45.1274 13.645C45.1011 13.4604 45.0615 13.2891 45.0088 13.1309H53.0771C53.3936 13.1309 53.644 13.2363 53.8286 13.4473C54.0132 13.6582 54.1055 13.8955 54.1055 14.1592ZM39.4717 8.46387C39.4717 8.04199 39.6035 7.58057 39.8672 7.07959C40.1309 6.57861 40.3418 6.30176 40.5 6.24902C40.6582 6.30176 40.8691 6.57861 41.1328 7.07959C41.3965 7.58057 41.5283 8.04199 41.5283 8.46387C41.5283 8.78027 41.4229 9.03076 41.2119 9.21533C41.001 9.3999 40.7637 9.49219 40.5 9.49219C40.2363 9.49219 39.999 9.3999 39.7881 9.21533C39.5771 9.03076 39.4717 8.78027 39.4717 8.46387ZM26.8945 14.1592C26.8945 13.8955 26.9868 13.6582 27.1714 13.4473C27.356 13.2363 27.6064 13.1309 27.9229 13.1309H35.9912C35.9385 13.2891 35.8989 13.4604 35.8726 13.645C35.8462 13.8296 35.833 14.001 35.833 14.1592C35.833 14.3174 35.8462 14.4624 35.8726 14.5942C35.8989 14.7261 35.9121 14.8711 35.9121 15.0293L26.8945 14.2383V14.1592ZM10.4414 59.8799H6.24902V32.5898H10.4414C11.127 32.5898 11.7202 32.8271 12.2212 33.3018C12.7222 33.7764 12.9727 34.3564 12.9727 35.042V57.3486C12.9727 58.0342 12.7222 58.6274 12.2212 59.1284C11.7202 59.6294 11.127 59.8799 10.4414 59.8799ZM21.6738 62.4111L25.1543 57.9023C25.3125 57.7441 25.4839 57.6123 25.6685 57.5068C25.853 57.4014 26.0508 57.3223 26.2617 57.2695C26.4727 57.2695 26.6836 57.2959 26.8945 57.3486C27.1055 57.4014 27.29 57.4805 27.4482 57.5859C27.8174 57.9023 28.0283 58.2715 28.0811 58.6934C28.1338 59.1152 28.0283 59.5107 27.7646 59.8799L24.2051 64.3887C23.8887 64.7578 23.5195 64.9688 23.0977 65.0215C22.6758 65.0742 22.2803 64.9424 21.9111 64.626C21.542 64.3623 21.3311 64.0063 21.2783 63.5581C21.2256 63.1099 21.3574 62.7275 21.6738 62.4111ZM24.9961 70.0049C24.627 69.7412 24.416 69.3853 24.3633 68.937C24.3105 68.4888 24.416 68.0801 24.6797 67.7109L26.1035 65.8916L29.6631 61.4619C29.8213 61.251 29.9927 61.0928 30.1772 60.9873C30.3618 60.8818 30.5596 60.8291 30.7705 60.8291C30.9814 60.7764 31.1924 60.7896 31.4033 60.8687C31.6143 60.9478 31.7988 61.04 31.957 61.1455C32.1152 61.3037 32.2471 61.4751 32.3525 61.6597C32.458 61.8442 32.5371 62.042 32.5898 62.2529C32.5898 62.4639 32.5635 62.6748 32.5107 62.8857C32.458 63.0967 32.3525 63.2812 32.1943 63.4395L28.7139 67.9482L27.29 69.6885C26.9736 70.0576 26.6045 70.2686 26.1826 70.3213C25.7607 70.374 25.3652 70.2686 24.9961 70.0049ZM30.9287 71.7451C30.5596 71.4814 30.3486 71.1255 30.2959 70.6772C30.2432 70.229 30.3486 69.8203 30.6123 69.4512L34.1719 64.9424C34.2773 64.7842 34.4355 64.6523 34.6465 64.5469C34.8574 64.4414 35.0684 64.3887 35.2793 64.3887C35.2793 64.3887 35.2925 64.3755 35.3188 64.3491C35.3452 64.3228 35.3848 64.3096 35.4375 64.3096C35.5957 64.3096 35.7671 64.3491 35.9517 64.4282C36.1362 64.5073 36.3076 64.5996 36.4658 64.7051C36.624 64.8105 36.7559 64.9556 36.8613 65.1401C36.9668 65.3247 37.0195 65.5488 37.0195 65.8125C37.0723 66.0234 37.0723 66.2212 37.0195 66.4058C36.9668 66.5903 36.8613 66.7881 36.7031 66.999L33.1436 71.4287C32.8799 71.7979 32.5239 72.0088 32.0757 72.0615C31.6274 72.1143 31.2451 72.0088 30.9287 71.7451ZM38.3643 74.1182C38.2061 74.2764 38.0347 74.4082 37.8501 74.5137C37.6655 74.6191 37.4678 74.6719 37.2568 74.6719C37.0459 74.7246 36.835 74.7246 36.624 74.6719C36.4131 74.6191 36.2285 74.5137 36.0703 74.3555C35.9121 74.25 35.7803 74.105 35.6748 73.9204C35.5693 73.7358 35.5166 73.5381 35.5166 73.3271C35.4639 73.0635 35.4639 72.8394 35.5166 72.6548C35.5693 72.4702 35.6748 72.2725 35.833 72.0615L38.6807 68.502C38.8389 68.291 39.0234 68.1328 39.2344 68.0273C39.4453 67.9219 39.6826 67.8691 39.9463 67.8691C40.1045 67.8691 40.2759 67.8955 40.4604 67.9482C40.645 68.001 40.79 68.1064 40.8955 68.2646C41.2646 68.5283 41.4756 68.8843 41.5283 69.3325C41.5811 69.7808 41.4756 70.1631 41.2119 70.4795L38.3643 74.1182ZM60.5918 59.6426C60.3281 60.0117 59.9722 60.2095 59.5239 60.2358C59.0757 60.2622 58.667 60.1172 58.2979 59.8008L50.0713 52.6816C49.8076 52.418 49.5044 52.2993 49.1616 52.3257C48.8188 52.3521 48.542 52.4971 48.3311 52.7607C48.0674 53.0244 47.9487 53.3276 47.9751 53.6704C48.0015 54.0132 48.1465 54.29 48.4102 54.501L56.7158 61.6992L58.4561 63.2021C58.7725 63.4658 58.9438 63.8218 58.9702 64.27C58.9966 64.7183 58.8779 65.127 58.6143 65.4961C58.2979 65.8125 57.9155 65.9839 57.4673 66.0103C57.019 66.0366 56.6367 65.918 56.3203 65.6543L50.2295 60.4336L47.1445 57.7441C46.8809 57.4805 46.5776 57.3618 46.2349 57.3882C45.8921 57.4146 45.6152 57.5596 45.4043 57.8232C45.1934 58.0869 45.1011 58.3901 45.1274 58.7329C45.1538 59.0757 45.2725 59.3525 45.4834 59.5635L52.9189 66.0498C53.0771 66.1553 53.209 66.3003 53.3145 66.4849C53.4199 66.6694 53.4727 66.8936 53.4727 67.1572C53.5254 67.3682 53.5122 67.5659 53.4331 67.7505C53.354 67.9351 53.2354 68.1064 53.0771 68.2646C52.8135 68.6338 52.4575 68.8315 52.0093 68.8579C51.561 68.8843 51.1523 68.7656 50.7832 68.502L48.9639 66.8408L46.5117 64.7051L44.5342 63.0439C44.2705 62.7803 43.9673 62.6616 43.6245 62.688C43.2817 62.7144 43.0049 62.8594 42.7939 63.123C42.583 63.3867 42.4775 63.6899 42.4775 64.0327C42.4775 64.3755 42.6094 64.6523 42.873 64.8633L48.3311 69.6094C48.6475 69.873 48.832 70.229 48.8848 70.6772C48.9375 71.1255 48.8057 71.5342 48.4893 71.9033C48.2256 72.2197 47.8564 72.3911 47.3818 72.4175C46.9072 72.4438 46.5117 72.3252 46.1953 72.0615L43.9805 70.084C44.0859 69.3984 44.0068 68.7129 43.7432 68.0273C43.4795 67.3418 43.0576 66.7617 42.4775 66.2871C42.0557 65.9707 41.5811 65.7334 41.0537 65.5752C40.5264 65.417 39.999 65.3643 39.4717 65.417C39.4189 64.8896 39.2607 64.4019 38.9971 63.9536C38.7334 63.5054 38.3906 63.0967 37.9688 62.7275C37.5469 62.4111 37.0854 62.1738 36.5845 62.0156C36.0835 61.8574 35.5693 61.8311 35.042 61.9365C34.9365 61.3564 34.752 60.8423 34.4883 60.394C34.2246 59.9458 33.8818 59.5635 33.46 59.2471C33.0381 58.8779 32.5635 58.6274 32.0361 58.4956C31.5088 58.3638 31.0078 58.3242 30.5332 58.377C30.4277 57.8496 30.2563 57.3486 30.019 56.874C29.7817 56.3994 29.4521 56.0039 29.0303 55.6875C28.5557 55.3184 28.0679 55.0679 27.5669 54.936C27.0659 54.8042 26.5254 54.7646 25.9453 54.8174C25.418 54.8701 24.917 55.0283 24.4424 55.292C23.9678 55.5557 23.5723 55.8984 23.2559 56.3203L21.1992 58.9307L18.7471 56.9531C18.5361 56.7949 18.2988 56.6631 18.0352 56.5576C17.7715 56.4521 17.5078 56.3994 17.2441 56.3994H15.4248V35.9912H18.7471C18.8525 35.9912 18.958 35.9912 19.0635 35.9912C19.1689 35.9912 19.248 35.9648 19.3008 35.9121L22.7021 34.1719C23.0186 34.0664 23.3481 33.9609 23.6909 33.8555C24.0337 33.75 24.3633 33.6973 24.6797 33.6973H36.3867L30.6123 40.9746C30.4014 41.2383 30.2563 41.5283 30.1772 41.8447C30.0981 42.1611 30.085 42.4775 30.1377 42.7939C30.1904 43.1104 30.2827 43.4004 30.4146 43.6641C30.5464 43.9277 30.7441 44.165 31.0078 44.376L31.8779 45.0879C32.5107 45.5625 33.1963 45.9053 33.9346 46.1162C34.6729 46.3271 35.4375 46.3799 36.2285 46.2744C36.9668 46.1689 37.6787 45.9316 38.3643 45.5625C39.0498 45.1934 39.6299 44.7188 40.1045 44.1387L42.1611 41.5283L60.4336 57.3486C60.5918 57.5068 60.7236 57.6782 60.8291 57.8628C60.9346 58.0474 60.9873 58.2451 60.9873 58.4561C60.9873 58.667 60.9609 58.8779 60.9082 59.0889C60.8555 59.2998 60.75 59.4844 60.5918 59.6426Z\" fill=\"white\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWe represent real people\u2014not corporations\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262fbee elementor-widget elementor-widget-button\" data-id=\"262fbee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#injury\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">START TODAY<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a9f1cec e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"a9f1cec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f5c958 elementor-widget elementor-widget-image\" data-id=\"0f5c958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"799\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/justice-balance-law.png\" class=\"attachment-full size-full wp-image-38492 lazyload\" alt=\"\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/justice-balance-law.png 800w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/justice-balance-law-80x80.png 80w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/justice-balance-law-768x767.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/justice-balance-law-300x300.png 300w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/justice-balance-law-600x599.png 600w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/justice-balance-law-100x100.png 100w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/799;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63f6af0 e-flex e-con-boxed e-con e-parent\" data-id=\"63f6af0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5362da3 elementor-widget elementor-widget-heading\" data-id=\"5362da3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Local News Turns to L.A. LAW for Legal Perspective<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73269fd e-con-full e-flex e-con e-child\" data-id=\"73269fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8025249 elementor-widget elementor-widget-video\" data-id=\"8025249\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=aW4E5NneqEM&amp;list=PLE71axFzWNaukaaU274XBMqXISpu8sr7n&amp;index=6 &quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfe1f37 e-flex e-con-boxed e-con e-parent\" data-id=\"cfe1f37\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0143307 elementor-widget elementor-widget-heading\" data-id=\"0143307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Client Testimonials.Real Results. <span style=\"color: #FF6600\">Real People<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ead49e elementor-widget elementor-widget-text-editor\" data-id=\"8ead49e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>\u00a0<\/div><p>Hear from real clients across Connecticut who trusted L.A. LAW with their injury cases.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae73547 elementor-widget elementor-widget-html\" data-id=\"ae73547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Elfsight Google Reviews | L.A LAW Testimonials -->\n<script src=\"https:\/\/static.elfsight.com\/platform\/platform.js\" async><\/script>\n<div class=\"elfsight-app-3956382e-f905-48b0-a54c-304fa5f471a7\" data-elfsight-app-lazy><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3516ee77 e-flex e-con-boxed e-con e-parent\" data-id=\"3516ee77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-328f26f elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"328f26f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequently Asked Questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10b704b5 elementor-widget elementor-widget-html\" data-id=\"10b704b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Elfsight FAQ | FAQs LA LAW - Medical Malpractice -->\n<script src=\"https:\/\/static.elfsight.com\/platform\/platform.js\" async><\/script>\n<div class=\"elfsight-app-b6b238fb-9f63-4548-a438-a492555d8e49\" data-elfsight-app-lazy><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d0882e e-flex e-con-boxed e-con e-parent\" data-id=\"0d0882e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aa419c8 e-con-full e-flex e-con e-child\" data-id=\"aa419c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-07ce8d6 e-con-full e-flex e-con e-child\" data-id=\"07ce8d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c032f elementor-widget elementor-widget-heading\" data-id=\"a3c032f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">You May Also Need Help With These Injury Claims<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6117475 elementor-widget elementor-widget-text-editor\" data-id=\"6117475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We don\u2019t just handle car accidents\u2014our attorneys represent injury victims across Connecticut in a wide range of serious cases.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-154e20a e-con-full e-flex e-con e-child\" data-id=\"154e20a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89a527b elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"89a527b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Brain Injuries&quot;,&quot;_id&quot;:&quot;f9b5854&quot;},{&quot;slide_title&quot;:&quot;Wrongful Death&quot;,&quot;_id&quot;:&quot;1185748&quot;},{&quot;slide_title&quot;:&quot;Mototcycle Accidents&quot;,&quot;_id&quot;:&quot;55463b7&quot;},{&quot;slide_title&quot;:&quot;Truck Accidents&quot;,&quot;_id&quot;:&quot;c381a74&quot;},{&quot;slide_title&quot;:&quot;Dog Bite&quot;,&quot;_id&quot;:&quot;540a24e&quot;},{&quot;slide_title&quot;:&quot;Pedestrian Accidents&quot;,&quot;_id&quot;:&quot;e893751&quot;},{&quot;slide_title&quot;:&quot;Workmans Comp&quot;,&quot;_id&quot;:&quot;ca40228&quot;},{&quot;slide_title&quot;:&quot;Slip and Fall&quot;,&quot;_id&quot;:&quot;d686d92&quot;},{&quot;slide_title&quot;:&quot;Medical Malpractice&quot;,&quot;_id&quot;:&quot;539ae1e&quot;}],&quot;slides_to_show&quot;:&quot;2&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79fd5d1 e-flex e-con-boxed e-con e-child\" data-id=\"79fd5d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46a10fc elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"46a10fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/traumatic-brain-injury-connecticut-personal-injury-lawyer-768x456.png\" class=\"attachment-medium size-medium wp-image-38093 lazyload\" alt=\"Doctor reviewing multiple brain scan images to assess trauma \u2013 legal support for traumatic brain injury victims in Connecticut.\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/traumatic-brain-injury-connecticut-personal-injury-lawyer-768x456.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/traumatic-brain-injury-connecticut-personal-injury-lawyer-1170x694.png 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bdde3d elementor-widget elementor-widget-heading\" data-id=\"7bdde3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Brain Injuries<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f79531 elementor-widget elementor-widget-text-editor\" data-id=\"0f79531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We fight for Connecticut clients suffering traumatic brain injuries, securing compensation for long-term care, lost wages, and life changes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8798240 elementor-widget elementor-widget-button\" data-id=\"8798240\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/connecticut-brain-injury-lawyer\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de048f9 e-flex e-con-boxed e-con e-child\" data-id=\"de048f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91cc9fe elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"91cc9fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/personal-injury-lawyer-consultation-connecticut-768x456.png\" class=\"attachment-medium size-medium wp-image-38089 lazyload\" alt=\"Woman in black dress holding white lilies at a wooden casket during a funeral, symbolizing a wrongful death case in Connecticut\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/personal-injury-lawyer-consultation-connecticut-768x456.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/personal-injury-lawyer-consultation-connecticut-1170x694.png 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb2dce9 elementor-widget elementor-widget-heading\" data-id=\"bb2dce9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wrongful Death<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35d4737 elementor-widget elementor-widget-text-editor\" data-id=\"35d4737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>When negligence leads to loss of life, our firm stands with grieving families to pursue wrongful death claims across Connecticut.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac37a1d elementor-widget elementor-widget-button\" data-id=\"ac37a1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/connecticut-wrongful-death-lawyer\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30e275e e-flex e-con-boxed e-con e-child\" data-id=\"30e275e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e402b8a elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"e402b8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/motorcycle-accident-connecticut-personal-injury-lawyer-768x456.png\" class=\"attachment-medium size-medium wp-image-38087 lazyload\" alt=\"Wrecked motorcycle lying on the road after a serious collision \u2013 legal representation for motorcycle accident victims in Connecticut.\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/motorcycle-accident-connecticut-personal-injury-lawyer-768x456.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/motorcycle-accident-connecticut-personal-injury-lawyer-1170x694.png 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d0b377 elementor-widget elementor-widget-heading\" data-id=\"8d0b377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Motorcycle Accidents<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77e7cd7 elementor-widget elementor-widget-text-editor\" data-id=\"77e7cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>If you\u2019ve been injured on a motorcycle, we fight bias and negligence to get Connecticut riders the justice they deserve.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22c034b elementor-widget elementor-widget-button\" data-id=\"22c034b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/motorcycle-accident-attorney-ct\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-681bdd9 e-flex e-con-boxed e-con e-child\" data-id=\"681bdd9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6ae923 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"a6ae923\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/truck-accident-connecticut-personal-injury-lawyer-768x456.png\" class=\"attachment-medium size-medium wp-image-38088 lazyload\" alt=\"Semi-truck crashed into a guardrail on a Connecticut highway with tow truck on site \u2013 legal help for truck accident victims.\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/truck-accident-connecticut-personal-injury-lawyer-768x456.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/truck-accident-connecticut-personal-injury-lawyer-1170x694.png 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6ec654 elementor-widget elementor-widget-heading\" data-id=\"a6ec654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Truck Accidents<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1a70b8 elementor-widget elementor-widget-text-editor\" data-id=\"a1a70b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our attorneys take on commercial trucking companies after devastating accidents on Connecticut roads and highways.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f06bda1 elementor-widget elementor-widget-button\" data-id=\"f06bda1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/connecticut-truck-accident-lawyer\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-155ded9 e-flex e-con-boxed e-con e-child\" data-id=\"155ded9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27f7a0f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"27f7a0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/Dog-Bite-Injury-\u2013-Connecticut-Personal-Injury-Attorneys-768x456.webp\" class=\"attachment-medium size-medium wp-image-38086 lazyload\" alt=\"Close-up of an aggressive dog biting a person\u2019s hand \u2013 legal help for dog bite victims in Connecticut.\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/Dog-Bite-Injury-\u2013-Connecticut-Personal-Injury-Attorneys-768x456.webp 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/Dog-Bite-Injury-\u2013-Connecticut-Personal-Injury-Attorneys-1170x694.webp 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce099b6 elementor-widget elementor-widget-heading\" data-id=\"ce099b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dog Bite<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e693c elementor-widget elementor-widget-text-editor\" data-id=\"27e693c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Under Connecticut\u2019s strict liability laws, we help dog bite victims pursue compensation for medical care and emotional trauma.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84f39fc elementor-widget elementor-widget-button\" data-id=\"84f39fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/dog-bite-attorney-ct\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-816ecbd e-flex e-con-boxed e-con e-child\" data-id=\"816ecbd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a034cd elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0a034cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/pedestrian-crosswalk-accident-connecticut-lawyer-1-768x456.png\" class=\"attachment-medium size-medium wp-image-38091 lazyload\" alt=\"Woman crossing a city street at a crosswalk with traffic nearby \u2013 legal services for pedestrian accident victims in Connecticut.\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/pedestrian-crosswalk-accident-connecticut-lawyer-1-768x456.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/pedestrian-crosswalk-accident-connecticut-lawyer-1-1170x694.png 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed4174 elementor-widget elementor-widget-heading\" data-id=\"7ed4174\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pedestrian Accidents<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07c3ff2 elementor-widget elementor-widget-text-editor\" data-id=\"07c3ff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>If you were hit by a vehicle while walking, we fight to recover compensation for injured pedestrians throughout Connecticut.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25a36c6 elementor-widget elementor-widget-button\" data-id=\"25a36c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/pedestrian-accident-lawyer-ct\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"7\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74f67e6 e-flex e-con-boxed e-con e-child\" data-id=\"74f67e6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06088d7 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"06088d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/construction-site-injury-connecticut-workers-comp-lawyer-768x456.png\" class=\"attachment-medium size-medium wp-image-38092 lazyload\" alt=\"Two construction workers wearing hard hats and safety gear talking at a job site \u2013 legal assistance for workplace injury claims in Connecticut.\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/construction-site-injury-connecticut-workers-comp-lawyer-768x456.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/construction-site-injury-connecticut-workers-comp-lawyer-1170x694.png 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48bf4af elementor-widget elementor-widget-heading\" data-id=\"48bf4af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Workmans Comp<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02aff32 elementor-widget elementor-widget-text-editor\" data-id=\"02aff32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Injured on the job? We handle workers\u2019 comp and third-party claims to protect your income and your future.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f8d8d7 elementor-widget elementor-widget-button\" data-id=\"9f8d8d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/connecticut-workers-compensation-lawyer\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"8\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71e8e01 e-flex e-con-boxed e-con e-child\" data-id=\"71e8e01\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea5b9c5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ea5b9c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/slip-and-fall-accident-stairs-personal-injury-768x456.png\" class=\"attachment-medium size-medium wp-image-38098 lazyload\" alt=\"Woman slipping and falling on staircase, holding her back in pain, with papers scattered around.\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-832e48b elementor-widget elementor-widget-heading\" data-id=\"832e48b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Slip and Fall<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d33c8f7 elementor-widget elementor-widget-text-editor\" data-id=\"d33c8f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hurt on someone else\u2019s property? We hold negligent property owners accountable for unsafe conditions that lead to serious falls.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0e6a66 elementor-widget elementor-widget-button\" data-id=\"c0e6a66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/slip-and-fall-lawyer-connecticut\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"9\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 9\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e00431e e-flex e-con-boxed e-con e-child\" data-id=\"e00431e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8fbc852 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"8fbc852\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"456\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/medical-malpractice-lawyer-connecticut-personal-injury-768x456.png\" class=\"attachment-medium size-medium wp-image-38096 lazyload\" alt=\"Gavel, stethoscope, and prescription bottle on a desk \u2013 legal services for medical malpractice victims in Connecticut.\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/medical-malpractice-lawyer-connecticut-personal-injury-768x456.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/medical-malpractice-lawyer-connecticut-personal-injury-1170x694.png 1170w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 768px; --smush-placeholder-aspect-ratio: 768\/456;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f2d372 elementor-widget elementor-widget-heading\" data-id=\"7f2d372\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Medical Malpractice<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c6b92a elementor-widget elementor-widget-text-editor\" data-id=\"8c6b92a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>If a doctor\u2019s mistake caused you harm, our medical malpractice attorneys will hold healthcare providers accountable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fe3dda elementor-widget elementor-widget-button\" data-id=\"6fe3dda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/medical-malpractice-attorney-ct\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEARN MORE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-left\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M34.52 239.03L228.87 44.69c9.37-9.37 24.57-9.37 33.94 0l22.67 22.67c9.36 9.36 9.37 24.52.04 33.9L131.49 256l154.02 154.75c9.34 9.38 9.32 24.54-.04 33.9l-22.67 22.67c-9.37 9.37-24.57 9.37-33.94 0L34.52 272.97c-9.37-9.37-9.37-24.57 0-33.94z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00f3ximo\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64cb89e e-flex e-con-boxed e-con e-parent\" data-id=\"64cb89e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ae9ddd elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"2ae9ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Turning Injury Into Justice<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cb6c5b elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3cb6c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our legal team has recovered millions for clients injured in car accidents, slip and falls, dog bites, and more. Explore recent victories that show our commitment to justice\u2014and getting the maximum compensation you deserve.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ce8d08 elementor-widget elementor-widget-button\" data-id=\"8ce8d08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lalawct.com\/contact-personal-injury-lawyer-ct\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">GET A FREE CONSULTATION<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3058d11e e-con-full e-flex e-con e-parent\" data-id=\"3058d11e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-129c898d elementor-widget elementor-widget-image-carousel\" data-id=\"129c898d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/468155207_17886119016150918_3214933712147958242_n.jpg\" alt=\"468155207_17886119016150918_3214933712147958242_n\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/469177518_17887027665150918_9037818822775105586_n.jpg\" alt=\"469177518_17887027665150918_9037818822775105586_n\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/445413325_17863175007150918_8690403410942539772_n.jpg\" alt=\"445413325_17863175007150918_8690403410942539772_n\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/450107002_17867842539150918_835261487850931774_n.jpg\" alt=\"450107002_17867842539150918_835261487850931774_n\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1080px; --smush-placeholder-aspect-ratio: 1080\/1080;\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-903adbb e-flex e-con-boxed e-con e-parent\" data-id=\"903adbb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ad88a19 e-con-full e-flex e-con e-child\" data-id=\"ad88a19\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6ed07c7 e-con-full e-flex e-con e-child\" data-id=\"6ed07c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-221f28b elementor-widget elementor-widget-text-editor\" data-id=\"221f28b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Subscribe To Our Newsletter!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7328d87 elementor-widget__width-initial elementor-widget-widescreen__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7328d87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Stay informed on Connecticut personal injury laws, case updates, and legal tips to protect your rights\u2014straight to your inbox.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25cb2d0 elementor-widget__width-initial elementor-widget-widescreen__width-initial elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"25cb2d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"38547\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"25cb2d0\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"CT Medical Malpractice Attorneys | LA LAW\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"38547\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SEND<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fe3962f e-flex e-con-boxed e-con e-parent\" data-id=\"4fe3962f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-26ad3fd7 e-con-full e-flex e-con e-child\" data-id=\"26ad3fd7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2855a844 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2855a844\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/lalawct.com\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"2230\" height=\"1012\" data-src=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho.png\" class=\"attachment-full size-full wp-image-39095 lazyload\" alt=\"la law logo\" data-srcset=\"https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho.png 2230w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-768x349.png 768w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-1536x697.png 1536w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-2048x929.png 2048w, https:\/\/lalawct.com\/wp-content\/uploads\/2025\/05\/la-law-loho-600x272.png 600w\" data-sizes=\"(max-width: 2230px) 100vw, 2230px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 2230px; --smush-placeholder-aspect-ratio: 2230\/1012;\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Serious accidents. Relentless insurance companies. We fight back for real people across Hartford, New Haven, and beyond.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5be40c31 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"5be40c31\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dce75a5 elementor-widget elementor-widget-heading\" data-id=\"2dce75a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">QUICK LINKS<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b6765cd elementor-widget elementor-widget-text-editor\" data-id=\"6b6765cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/lalawct.com\/connecticut-personal-injury-practice-areas\/\">Practice Areas<\/a><br \/><a href=\"https:\/\/lalawct.com\/client-testimonials\/\">Client Testimonials<\/a><br \/><a href=\"https:\/\/lalawct.com\/contact-connecticut-injury-lawyer\/\">Contact Us<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ad2a6f2 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"ad2a6f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a4dbf04 elementor-widget elementor-widget-heading\" data-id=\"7a4dbf04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">SOCIALS<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f90c64b elementor-widget elementor-widget-text-editor\" data-id=\"3f90c64b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.facebook.com\/people\/Lawyer-The-Lawyer\/61556617866591\/\" target=\"_blank\" rel=\"noopener\">Facebook<\/a><br \/><a href=\"https:\/\/www.instagram.com\/lawyerthelawyer\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a><br \/><a href=\"https:\/\/www.youtube.com\/@lawyerthelawyer\/videos\" target=\"_blank\" rel=\"noopener\">YouTube<\/a><br \/><a href=\"https:\/\/www.tiktok.com\/@lawyerthelawyer\" target=\"_blank\" rel=\"noopener\">Tik Tok<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f5605ad e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"6f5605ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a60fb5e elementor-widget elementor-widget-heading\" data-id=\"7a60fb5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">LEGAL<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33d30316 elementor-widget elementor-widget-text-editor\" data-id=\"33d30316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/lalawct.com\/privacy-policy\/\">Privacy Policy<\/a><br \/><a href=\"https:\/\/lalawct.com\/terms-of-service\/\">Terms of Service<\/a><br \/><a href=\"https:\/\/lalawct.com\/accesibility-statement\/\">Accesibility Statement<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24bb4ef1 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"24bb4ef1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-230bd169 elementor-widget elementor-widget-heading\" data-id=\"230bd169\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">LOCATIONS<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a1a2970 elementor-widget elementor-widget-text-editor\" data-id=\"6a1a2970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.google.com\/maps\/place\/L.A.+Law,+LLC\/@41.8304317,-72.743377,668m\/data=!3m2!1e3!4b1!4m6!3m5!1s0x89e7ad3417c64557:0x7f81c1c33e61de27!8m2!3d41.8304317!4d-72.7408021!16s%2Fg%2F11j22yqns3?entry=ttu&amp;g_ep=EgoyMDI1MTExNy4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">1 Regency Dr. Suite #302, Bloomfield, CT 06002<\/a>\u00a0<\/p><p><a href=\"https:\/\/www.google.com\/maps\/place\/L.A.+Law,+LLC\/@41.356239,-72.0981429,673m\/data=!3m2!1e3!5s0x89e60e61f38b9395:0x60e5190fb249ff3!4m16!1m9!3m8!1s0x89e60e61f36dc127:0x14a4a15bdd2ec9cd!2s125+Eugene+O&#039;Neill+Dr+Suite+140+Unit+%23217,+New+London,+CT+06320!3b1!8m2!3d41.356239!4d-72.095568!10e3!16s%2Fg%2F11mlq62x1v!3m5!1s0x89e60fd952368527:0xc7c4a804acb62780!8m2!3d41.356239!4d-72.095568!16s%2Fg%2F11ynfrx_zc?entry=ttu&amp;g_ep=EgoyMDI1MTExNy4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">125 Eugene O&#8217;Neill Drive Suite 140 #217\u00a0New London, CT 06320\u00a0<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d074a7f e-flex e-con-boxed e-con e-parent\" data-id=\"d074a7f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8de691e elementor-widget elementor-widget-heading\" data-id=\"8de691e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Copyright \u00a9 2026 | L.A. LAW  Rights Reserved.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1 Regency Dr. Suite #302, Bloomfield, CT 06002\u00a0|\u00a0860-595-3163 Medical Malpractice Lawyers Fighting for Injured Patients REQUEST A FREE CASE REVIEW When a Doctor\u2019s Mistake Causes Harm, You Deserve More Than an Apology\u200b Medical professionals are trusted to help\u2014not hurt. But when hospitals, doctors, or nurses fail to follow the standard of care, the consequences can [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-38547","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/pages\/38547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/comments?post=38547"}],"version-history":[{"count":46,"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/pages\/38547\/revisions"}],"predecessor-version":[{"id":46210,"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/pages\/38547\/revisions\/46210"}],"wp:attachment":[{"href":"https:\/\/lalawct.com\/es\/wp-json\/wp\/v2\/media?parent=38547"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}